{"id":2594,"date":"2021-01-12T12:54:47","date_gmt":"2021-01-12T12:54:47","guid":{"rendered":"https:\/\/artesaniadelapalma.com\/?page_id=2594"},"modified":"2021-01-12T14:05:57","modified_gmt":"2021-01-12T14:05:57","slug":"textilien","status":"publish","type":"page","link":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/","title":{"rendered":"Textilien"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595855261501{margin-bottom: 20px !important;padding-top: 40px !important;padding-bottom: 20px !important;background-color: #dddddd !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_empty_space][vc_column_text]<\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#bordados\">STICKEREI<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#seda\">SEIDE<\/a>| <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#lino\">LEINEN<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#lana\">WOLLE<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#croche\">H\u00c4KELN<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#traperas\">LAPPEN<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#frivolite\">FRIVOLIT\u00c9<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#macrame\">MAKRAMEE<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#trajes\">TRADITIONELLE KLEIDUNG<\/a> | <a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien#polainas\">GAMASCHEN<\/a><\/h4>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595854242876{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_column_text]<\/p>\n<h1>Textilhandwerk auf La Palma<\/h1>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text]Nachdem der Webstuhl im 16. Jahrhundert auf der Insel eingef\u00fchrt worden war, wurden die Stoffe vorwiegend zur Bekleidung verwendet, wobei Leinen und Seide f\u00fcr die feinsten Kleidungsst\u00fccke zu besonderen Anl\u00e4ssen und Wolle f\u00fcr den Schutz vor K\u00e4lte und Witterungseinfl\u00fcssen getragen wurden.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nGerade die in zwei und vier Schlingen hergestellten Wolldecken halfen den Bauern auf der Insel, die Winter zu \u00fcberstehen. Die gefl\u00fcgelten M\u00fctzen wiederum, die aus demselben Material gefertigt wurden, sch\u00fctzten die Bewohner vor der K\u00e4lte der Passatwinde.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nDer Webstuhl hatte seinerzeit sogar einen \u00fcbergeordneten Zweck: Er war eine nicht zu untersch\u00e4tzende Mitgift f\u00fcr die jungen heiratsf\u00e4higen Frauen der Insel.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nDas Leinen wurde neben der Herstellung von Kleidungsst\u00fccken vor allem auch zur Herstellung von T\u00fcchern aller Art f\u00fcr die Verwendung auf dem Land verarbeitet. Nat\u00fcrlich wurden auch S\u00e4cke aus Leinen hergestellt, um Weizen, Gerste oder Roggen zu sammeln und aufzubewahren &#8211; um es darin schlie\u00dflich zur M\u00fchle zu transportieren, damit es zu Gofio weiterverarbeitet werden konnte. Des Weiteren fertigte man aus diesem Naturstoff auch Satteltaschen, um die Nahrung f\u00fcr die Landarbeiter oder das zu s\u00e4ende Getreide auf das Feld zu bringen. Aus den Stoffresten wurden schlie\u00dflich Lumpen gewebt und als Decken verwendet.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nAus dem Ausschuss der Seidenkokons, die mit Koschenille, Reseda, Orchilla und anderen Naturprodukten gef\u00e4rbt wurden, fertigte man wundersch\u00f6ne Steppdecken mit Blumen oder Borte, die f\u00fcr La Palma charakteristisch sind.<br \/>\nAls kostbarste Faser galt jedoch die Seide, welche f\u00fcr Stolas, Messgew\u00e4nder und \u00dcberw\u00fcrfe verwendet, die sich auch bei Messen als Dekorationsauslagen eigneten, um die Kirchen zu schm\u00fccken und die Bauern an den gro\u00dfen Tagen des Jahres zu kleiden. F\u00fcr all dies gab es in jedem Haus einen Webstuhl.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nDas Klima und die nat\u00fcrlichen Ressourcen trugen dazu bei, dass auf der Insel haupts\u00e4chlich Seide, Leinen, Wolle und Lumpen hergestellt wurden, welche sich sp\u00e4ter angesichts der handwerklichen Perfektion, die die Kunsthandwerker in einigen Gebieten bei der Aus\u00fcbung dieser Webarbeiten erreichten, auf drei Stoffe reduzierten: auf Seide in der Gemeinde El Paso, auf Leinen in den Gemeinden Bre\u00f1a Alta, Bre\u00f1a Baja, Villa de Mazo und Garaf\u00eda sowie auf Wolle in der Gemeinde Garaf\u00eda. Die sogenannte \u201eTrapera\u201c, als der beliebteste Stoff, ist praktisch in allen Gemeinden der Insel zu finden.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nDas Textilhandwerk als Ganzes trug vielleicht mehr als jedes andere Kunsthandwerk dazu bei, das allt\u00e4gliche Leben der Bewohner zu versch\u00f6nern.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595855032948{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;bordados&#8220;][vc_column][vc_column_text]<\/p>\n<h2>STICKEREI<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1289&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Die Stickerei nimmt einen bedeutenden Bereich des Kunsthandwerks auf La Palma ein. Sie ist vor allem auf Trachtenanz\u00fcge, Tischdecken, Kirchenschmuck, Hausdekor und andere Textilien zu finden und zeugt von einer einzigartigen Tradition, die allm\u00e4hlich zu einer wichtigen Einnahmequelle geworden ist, die kreativen Entwicklungen und Verfeinerungen handwerklicher Art einen enormen Vorschub leistete.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;8&#8242; down=&#8220;]<br \/>\nLetztlich haben sich drei Techniken der Stickerei auf La Palma durchgesetzt und sind am h\u00e4ufigsten zu finden: Richelieu, Relief und verlorener Stich.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;8&#8242; down=&#8220;]<\/p>\n<p><strong>Richelieu:<\/strong> traditionell in Wei\u00df oder Beige gefertigt, zeichnet sich diese Technik durch ihre Schlaufen oder Girlanden aus, die durch eine weitere Luftschlaufe miteinander verbunden sind, was dem Stoff eine unverwechselbare Eleganz verleiht.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;8&#8242; down=&#8220;]<br \/>\nBei der <strong>Relief-Stickerei<\/strong> werden ausgef\u00fcllte Motive mit geraden oder schr\u00e4gen Stichen senkrecht zu den Stichen der F\u00fcllung gestickt; sie wird vor allem beim Sticken von Blumen, Bl\u00e4ttern und Initialen verwendet.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;8&#8242; down=&#8220;]<br \/>\nDer <strong>verlorene Stich<\/strong> wird mit progressiv \u00fcbereinander liegenden Stichen ausgef\u00fchrt, die durch die Intensit\u00e4t der Fadenfarbe unterschiedliche Schattierungen erzeugen.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;8&#8242; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595857744795{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;seda&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>Seide<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;153&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Mit der Eingliederung der Insel La Palma in die Krone von Kastilien, Ende des 15. Jahrhunderts, kam die Seidenverarbeitung aus Portugal und Andalusien auf die Insel. Und wer sich das Handwerk der Seidenherstellung und Verarbeitung heute, nach mehr als f\u00fcnf Jahrhunderten, ansieht, begibt sich auf eine Zeitreise und erlebt einen Herstellungsprozess, der immer noch vollst\u00e4ndig manuell durchgef\u00fchrt wird und daher heute in Europa einzigartig ist.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>Heutzutage wird dieses Kunsthandwerk immer noch auf die gleiche Art und Weise in der Seidenwerkstatt der Seidenspinnerinnen in der Gemeinde El Paso ausge\u00fcbt, wo sich die traditionelle Herstellung von Seide und deren Verarbeitung bis heute erhalten hat.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>Dabei wird die Seide wie vor Jahrhunderten mithilfe eines alten und einfachen Verfahrens gesponnen: Die Seidenkokons werden zun\u00e4chst in einem auf offenem Feuer stehenden Kupferkessel erhitzt und die einzelnen aus den Kokons gel\u00f6sten F\u00e4den anschliessend auf einem traditionellen Seidenwebstuhl aufgezogen und durch Drehen auf eine Spindel zu einem Seidenstrang verwoben.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595938774466{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;lino&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>Leinen<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;260&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Das intensive Blau des Leinens \u00fcberflutete im Mai die G\u00e4rten der Bewohner auf La Palma. Der Anblick seiner blau-gr\u00fcnen Rechtecke war und ist von \u00fcberw\u00e4ltigender Sch\u00f6nheit. Wie sonst auch wird auf dieser Insel auch diesmal Zweckm\u00e4\u00dfigkeit ganz selbstverst\u00e4ndlich mit feinstem \u00e4sthetischen Empfinden kombiniert. Denn es war sch\u00f6n und es war allt\u00e4glich.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596014532481{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;lana&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>Wolle<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;262&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Heutzutage stellt kaum noch jemand Wolle her auf La Palma. Auch gibt es nicht viele Schafherden auf der Insel, ausser in den Gemeinden El Paso und Garaf\u00eda. Kleidung aus Wolle war jedoch bis in die erste H\u00e4lfte des 20. Jahrhunderts Teil des t\u00e4glichen Lebens. So war es damals gerade im l\u00e4ndlicheren Bereich \u00fcblich, sich ein paar Schafe zu halten. Auf diese Weise hatte man immer nat\u00fcrlichen D\u00fcnger f\u00fcr die Felder, Milch zur K\u00e4seherstellung sowie eben Wolle zum Weben von Anz\u00fcgen, Decken, R\u00f6cken, Str\u00fcmpfen oder M\u00fctzen.<br \/>\n[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>Der Prozess der Umwandlung der Wolle zum fertigen Produkt wurde komplett zu Hause durchgef\u00fchrt. Die Schafe wurden geschoren, die Wolle wurde mit Seife gewaschen und dann auf einer Steinmauer zum Trocknen in die Sonne gelegt. Meist waren es die Gro\u00dfm\u00fctter, die sie dann ausk\u00e4mmten und aufwickelten. Dazu legten sie eine Wollflocke in ein Spinnrad aus Rohr oder Holz, das an einem Ende aufgespalten war. Von dort wurde es zur Spindel gef\u00fchrt, mit der es gesponnen wurde. Dann machten sie Str\u00e4nge und zogen sie wieder auf, so dass die Wolle bereit war, am Webstuhl verarbeitet zu werden, entweder in ihrer urspr\u00fcnglichen Farbe oder mit nat\u00fcrlichen Farbstoffen gef\u00e4rbt.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596016415126{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;croche&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>H\u00c4KELN<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;269&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Das H\u00e4keln gilt als ein besonders einfaches und angenehmes Kunsthandwerk, denn es bietet in seinen verschiedenen Techniken schnelle Ergebnisse.<br \/>\n[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>So wird H\u00e4keln \u00fcberall auf der Insel praktiziert, obwohl die \u00fcberwiegende Mehrheit der Frauen, die es praktizieren, es f\u00fcr den Eigenbedarf tun, ohne es zu verkaufen. In einigen Gegenden auf La Palma werden noch immer alte traditionelle Muster in Bettgarnituren, Altart\u00fcchern, Vorh\u00e4ngen, Tagesdecken und Spitzen verarbeitet, in die teilweise durch den Einfluss neuerer Mustervorlagen und Techniken neue Qualit\u00e4ten eingearbeitet werden.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596017769587{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;traperas&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>Lappen<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;355&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]In den H\u00e4usern der Bewohner auf La Palma wurde kein einziger Fetzen weggeworfen, egal wie abgenutzt er war. Sie wurden in feine Streifen geschnitten und zur weiteren Verarbeitung verwendet, um etwa Putzlappen herzustellen, die heute nat\u00fcrlich auch aus neuen Stoffen hergestellt werden.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nTeppiche, Vorh\u00e4nge, Decken, Taschen, Rucks\u00e4cke, Wandteppiche sowie Tagesdecken wurden und werden auch in dieser Technik hergestellt.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596018289382{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;frivolite&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>Frivolit\u00e9<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1295&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Die Arbeit mit dem Schiffchen, auch Frivolit\u00e9 genannt, ist eine Fortsetzung des H\u00e4kelns. Es setzt sich aus Knoten und Gondeln zusammen, die Ringe, Kreise oder Halbkreise bilden. Die Anordnung dieser Formen ergibt die verschiedenen Arten und Muster. Der Name ist franz\u00f6sischen Ursprungs und wurde in fast allen europ\u00e4ischen L\u00e4ndern \u00fcbernommen. Sie wird auf einer harten Unterlage oder direkt auf der Hand mit einem Schiffchen aus Knochen oder Holz ausgef\u00fchrt, das aus zwei Lamellen in Form einer l\u00e4nglichen Olive besteht, die in der Mitte verbunden sind und deren Enden spitz zulaufen.<br \/>\n[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nDer verwendete Faden variiert je nach Verwendungszweck, der vom Seidentaschentuch bis zur Verzierung der Auslagent\u00fccher eines Neugeborenen reichen kann.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596018815365{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;macrame&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>MAKRAMEE<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;278&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Der Begriff Makramee wird f\u00fcr bestimmte Arbeiten verwendet, die mit Hilfe von Knoten und dem Flechten von F\u00e4den hergestellt werden. Makramee ist eins der interessantesten und vielseitigsten Kunsthandwerke, da es zur Dekoration der unterschiedlichsten Gegenst\u00e4nde eingesetzt werden kann. Die hohe Festigkeit des Produktes tr\u00e4gt auch heute noch zu einer weiten Verbreitung bei. Alles, was f\u00fcr seine Ausf\u00fchrung ben\u00f6tigt wird, ist ein Faden und ein einfaches kleines Kissen.<br \/>\n[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\nGerade das feingearbeitete Makramee erscheint in reichlicher Form in zahlreichen Produkten, wie beispielsweise auf Handt\u00fccher, Bettdecken, Schals und andere Kleidungsst\u00fccke. Wie das H\u00e4keln erfreut sich auch Makramee durch die relativ einfache Verarbeitung einer steten Beliebtheit im Bereich der Handarbeiten.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1596018873219{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;trajes&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>TRADITIONELLE KLEIDUNG<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1130&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Der Reichtum an Trachten auf La Palma ist vor allem durch die Vielfalt der Mikroklimata gegeben, die durch die einzigartige Beschaffenheit der Insel herrschen. Die Anpassung der Kost\u00fcme an das Klima und an die t\u00e4gliche T\u00e4tigkeit sowie die Verwendung der vorhandenen Materialien haben bis vor nicht allzu langer Zeit die Kleidung der Bewohner auf La Palma gepr\u00e4gt.<br \/>\n[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>Im Gro\u00dfen und Ganzen kann die traditionelle Kleidung auf La Palma in drei verschiedene Stile eingeteilt werden: die Gala-Kleidung, die Arbeitstracht sowie Umh\u00e4nge und R\u00f6cke aller Art.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\n<strong>Das Galakleid<\/strong> ist aus Seide und raffinierten Stoffen gefertigt, angereichert mit Stickereien, haupts\u00e4chlich auf den Unterr\u00f6cken und der Unterw\u00e4sche. Besonderes Augenmerk wird auf die \u00c4sthetik bei der Platzierung auf der Kleidung und den Accessoires gelegt. All dies verleiht ihm ein besonders elegantes Aussehen. Diese so ausstaffierten Accessoires wurden vor allem den alten Familienjuwelen beigelegt, die von Mutter zu Tochter und von Generation zu Generation weitergegeben werden. F\u00fcr deren Herstellung gab es auf La Palma im 17. Jahrhundert bedeutende Goldschmiedewerkst\u00e4tten, aus denen St\u00fccke mit barockem Design hervorgingen. Bei den heutigen Reproduktionen der Trachten ist der sogenannte Petillo leider in Vergessenheit geraten. Es ist ein dreieckiges St\u00fcck (Seiden-)Stoff, das oft mit Spitze verziert wurde und von den Frauen \u00fcber dem Kleid getragen wurde, um darauf die umgeh\u00e4ngten Schmuckst\u00fccke besser zur Geltung bringen zu k\u00f6nnen. Die Galakost\u00fcme unterscheiden sich von den Arbeitskost\u00fcmen durch das Fehlen von Haube und Sch\u00fcrze, der seitlichen Raffung des ersten Unterrocks und von eleganter und koketter Gaze, die erneuert und mit Verb\u00e4nden verziert wurde. Abgerundet wird das Kleid durch einen kleinen Hut mit Krempe auf der Stirn, der aus Weizenstroh besteht und mit Federn, B\u00e4ndern und Blumen verziert ist, deren Kordel unter dem Kopfschmuck verborgen ist.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p><strong>Der Arbeitsanzug<\/strong>, der den l\u00e4ndlichen Gemeinden vorbehalten war, wurde in der Regel aus Stoffen hergestellt, die auf eigenen Webst\u00fchlen gefertigt und mit lokalen Fasern entsprechend verarbeitet wurden. Zu den verwendeten Materialien geh\u00f6rten Wolle f\u00fcr den ersten Unterrock sowie Leinen f\u00fcr die Hemden, weitere Unterr\u00f6cke und Unterw\u00e4sche. Charakteristisch f\u00fcr den Arbeitsanzug sind die ausgepr\u00e4gten und seitlichen Raffungen des Rocks. Die seidenen Mieder oder Leibchen der Galakleider werden hier durch grobe Stoffe ersetzt, die aus denselben rustikalen Webst\u00fchlen stammen.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p><strong>Der Anzug <\/strong>mit Umhang und Rock besteht aus zwei ersten Umh\u00e4ngen, w\u00e4hrend der dritte oft wei\u00df, gleich- oder andersfarbig ist, \u00e4hnlich dem der bei den Galakleidern verwendet wird. Einer davon wird auf den Schultern oder auf dem Kopf platziert und bildet eine Haube im Mudejar-Stil, die in einigen F\u00e4llen durch einen niedrigen kegelf\u00f6rmigen Hut erg\u00e4nzt wird. Der Anzug mit Umhang und Rock ist ein einzigartiges Kleidungsst\u00fcck auf den Kanarischen Inseln.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<\/p>\n<p>Seide, Wolle, Leinen, Leder; Hut, Schuhe, Kn\u00f6pfe; Stickerei, Kn\u00e4uel und nat\u00fcrliche Farbstoffe&#8230; bilden den Beitrag des Kunsthandwerks auf La Palma zur Herstellung der traditionellen Kost\u00fcme der Insel.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;10&#8216; down=&#8220;]<br \/>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1597925436961{margin-top: 60px !important;margin-bottom: 40px !important;}&#8220; z_index=&#8220;&#8220; anchor=&#8220;polainas&#8220;][vc_column][vc_empty_space height=&#8220;42px&#8220;][vc_column_text]<\/p>\n<h2>GAMASCHEN<\/h2>\n<p>[\/vc_column_text][vc_empty_space][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1259&#8243; img_size=&#8220;full&#8220; qode_css_animation=&#8220;&#8220;][\/vc_column_inner][vc_column_inner width=&#8220;2\/3&#8243;][vc_column_text]Die Herstellung einer dieser Erg\u00e4nzungen der traditionellen M\u00e4nnertracht ist die Gamasche. Es ist eine Art Socke, welche das Bein unterhalb des Knies bis zum Spann bedeckt. Die traditionellen Gamaschen werden aus Wollgarn hergestellt und mit f\u00fcnf Stricknadeln gestrickt, so dass das St\u00fcck ganz ohne N\u00e4hte auskommt.<\/p>\n<p>[vc_separator type=&#8217;transparent&#8216; position=&#8217;center&#8216; color=&#8220; thickness=&#8220; up=&#8217;30&#8216; down=&#8220;]<\/p>\n<h6><\/h6>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;grid&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; z_index=&#8220;&#8220;][vc_column][vc_column_text]<\/p>\n<h6>Texto: \u00a9<strong><em> &#8222;Gu\u00eda de artesan\u00eda La Palma&#8220;.<\/em><\/strong> Myriam Cabrera, Mar\u00eda Victoria Hern\u00e1ndez y Vicente Blanco<\/h6>\n<p>[\/vc_column_text][vc_empty_space height=&#8220;30px&#8220;][vc_row_inner row_type=&#8220;row&#8220; type=&#8220;full_width&#8220; text_align=&#8220;left&#8220; css_animation=&#8220;&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;]\n\n\t<a href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/\" target=\"_self\" style=\"color: #ffffff;background-color: #f22f1d\" class=\"qode-btn qode-btn-medium qode-btn-solid qode-btn-custom-hover-bg qode-btn-custom-hover-color qode-btn-custom-icon-bg-hover-color qode-btn-icon qode-btn-icon-rotate\" data-hover-bg-color=\"#ffffff\" data-hover-color=\"#f22f1d\" >\n\t    <span class=\"qode-btn-text\">Andere Handwerksberufe<\/span><span class=\"qode-button-v2-icon-holder\" style=\"border-color: #ffffff;background-color: #f22f1d\" data-hover-icon-border-color=\"#f22f1d\" data-hover-icon-bg-color=\"#ffffff\"><i class=\"qodef-icon-linea-icon icon-arrows-circle-left qode-button-v2-icon-holder-inner\" ><\/i><\/span>\t<\/a>\n\n[\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8220;52px&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595855261501{margin-bottom: 20px !important;padding-top: 40px !important;padding-bottom: 20px !important;background-color: #dddddd !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_empty_space][vc_column_text] STICKEREI |&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2483,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Textilien - Artesan\u00eda de La Palma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Textilien - Artesan\u00eda de La Palma\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595855261501{margin-bottom: 20px !important;padding-top: 40px !important;padding-bottom: 20px !important;background-color: #dddddd !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_empty_space][vc_column_text] STICKEREI |...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/\" \/>\n<meta property=\"og:site_name\" content=\"Artesan\u00eda de La Palma\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-12T14:05:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"19\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/\",\"url\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/\",\"name\":\"Textilien - Artesan\u00eda de La Palma\",\"isPartOf\":{\"@id\":\"https:\/\/artesaniadelapalma.com\/#website\"},\"datePublished\":\"2021-01-12T12:54:47+00:00\",\"dateModified\":\"2021-01-12T14:05:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/artesaniadelapalma.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"traditionelle Kultur\",\"item\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bereiche des Kunsthandwerks\",\"item\":\"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Textilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artesaniadelapalma.com\/#website\",\"url\":\"https:\/\/artesaniadelapalma.com\/\",\"name\":\"Artesan\u00eda de La Palma\",\"description\":\"Artesan\u00eda de La Palma \/ Cabildo Insular de La Palma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/artesaniadelapalma.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Textilien - Artesan\u00eda de La Palma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/","og_locale":"de_DE","og_type":"article","og_title":"Textilien - Artesan\u00eda de La Palma","og_description":"[vc_row css_animation=&#8220;&#8220; row_type=&#8220;row&#8220; use_row_as_full_screen_section=&#8220;no&#8220; type=&#8220;full_width&#8220; angled_section=&#8220;no&#8220; text_align=&#8220;left&#8220; background_image_as_pattern=&#8220;without_pattern&#8220; css=&#8220;.vc_custom_1595855261501{margin-bottom: 20px !important;padding-top: 40px !important;padding-bottom: 20px !important;background-color: #dddddd !important;}&#8220; z_index=&#8220;&#8220;][vc_column][vc_empty_space][vc_column_text] STICKEREI |...","og_url":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/","og_site_name":"Artesan\u00eda de La Palma","article_modified_time":"2021-01-12T14:05:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"19\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/","url":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/","name":"Textilien - Artesan\u00eda de La Palma","isPartOf":{"@id":"https:\/\/artesaniadelapalma.com\/#website"},"datePublished":"2021-01-12T12:54:47+00:00","dateModified":"2021-01-12T14:05:57+00:00","breadcrumb":{"@id":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/textilien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/artesaniadelapalma.com\/de\/"},{"@type":"ListItem","position":2,"name":"traditionelle Kultur","item":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/"},{"@type":"ListItem","position":3,"name":"Bereiche des Kunsthandwerks","item":"https:\/\/artesaniadelapalma.com\/de\/traditionelle-kultur\/bereiche-des-kunsthandwerks\/"},{"@type":"ListItem","position":4,"name":"Textilien"}]},{"@type":"WebSite","@id":"https:\/\/artesaniadelapalma.com\/#website","url":"https:\/\/artesaniadelapalma.com\/","name":"Artesan\u00eda de La Palma","description":"Artesan\u00eda de La Palma \/ Cabildo Insular de La Palma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/artesaniadelapalma.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/pages\/2594"}],"collection":[{"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/comments?post=2594"}],"version-history":[{"count":4,"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/pages\/2594\/revisions"}],"predecessor-version":[{"id":2700,"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/pages\/2594\/revisions\/2700"}],"up":[{"embeddable":true,"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/pages\/2483"}],"wp:attachment":[{"href":"https:\/\/artesaniadelapalma.com\/de\/wp-json\/wp\/v2\/media?parent=2594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}